{"id":50139,"date":"2019-12-06T06:20:50","date_gmt":"2019-12-06T05:20:50","guid":{"rendered":"https:\/\/www.lhr-law.de\/?p=50139"},"modified":"2019-12-05T06:24:37","modified_gmt":"2019-12-05T05:24:37","slug":"vzbv-gegen-vodafone-keine-zusatzgebuehr-fuer-sepa-ueberweisungen","status":"publish","type":"post","link":"https:\/\/www.lhr-law.de\/en\/magazin\/wettbewerbsrecht-kartellrecht\/vzbv-gegen-vodafone-keine-zusatzgebuehr-fuer-sepa-ueberweisungen\/","title":{"rendered":"VZBV gegen Vodafone: Keine Zusatzgeb\u00fchr f\u00fcr SEPA-\u00dcberweisungen"},"content":{"rendered":"<p><em><img decoding=\"async\" class=\" wp-image-50248 alignleft\" src=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-621x414.jpg\" alt=\"\" width=\"456\" height=\"304\" srcset=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-621x414.jpg 621w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-620x413.jpg 620w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-768x512.jpg 768w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-1536x1024.jpg 1536w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2019\/11\/alistair-macrobert-8wMflrTLm2g-unsplash-scaled.jpg 2048w\" sizes=\"(max-width: 456px) 100vw, 456px\" \/>Seit 2018 d\u00fcrfen Unternehmen keine zus\u00e4tzlichen Entgelte f\u00fcr die Bezahlung via SEPA-\u00dcberweisungen, SEPA-Lastschriften oder Kredit- und Girokarten mehr fordern. <\/em><\/p>\n<p><em>Das Geb\u00fchrenverbot gilt auch f\u00fcr Altvertr\u00e4ge, die noch vor Inkrafttreten des<a href=\"https:\/\/www.lhr-law.de\/magazin\/wettbewerbsrecht-kartellrecht\/aufschlaege-fuer-kreditkarte-sepa-ueberweisung-lastschrift\">\u00a0\u201eGesetzes zur Umsetzung der Zweiten Zahlungsdiensterichtlinie\u201c <\/a>im Januar 2018 abgeschlossen wurden. <\/em><em>Das entschied das LG M\u00fcnchen I nach einer Klage des Verbraucherzentrale Bundesverbands (vzbv) gegen Vodafone Kabel Deutschland GmbH (LG M\u00fcnchen I, Urteil v. 24.09.2019, Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=33%20O%206578\/18\" title=\"LG M&uuml;nchen I, 24.09.2019 - 33 O 6578\/18: Zeitlicher Geltungsbereich von &sect; 270a BGB\">33 O 6578\/18<\/a>).<\/em><\/p>\n<h2>Zusatzentgelt von 2,50 Euro pro \u00dcberweisung<\/h2>\n<p>Seit Umsetzung der Zweiten Zahlungsdiensterichtlinie (RL 2015\/2366\/EU) zum 13.01.2018, wonach Unternehmen f\u00fcr die Bezahlung mit SEPA-\u00dcberweisungen, SEPA-Lastschriften oder Kredit- und Girokarten kein Entgelt verlangen d\u00fcrfen, differenzierte Vodafone zwischen Kunden mit Altvertr\u00e4gen und Neuvertr\u00e4gen. Der Kabelnetzbetreiber sah f\u00fcr Kunden mit \u00e4lteren Vertr\u00e4gen, die nicht per Lastschrift zahlten, eine \u201eSelbstzahlerpauschale\u201c von 2,50 Euro in den <a href=\"https:\/\/www.lhr-law.de\/taetigkeitsfelder\/allgemeine-geschaeftsbedingungen\">Allgemeinen Gesch\u00e4ftsbedingungen<\/a> vor. Die Pauschale sollte dabei f\u00fcr jede einzelne Zahlung f\u00e4llig werden und immer dann, wenn das Geld selbstst\u00e4ndig \u00fcberwiesen und nicht per Lastschrift eingezogen werde. Dagegen klagte der vzbv.<\/p>\n<h2><strong>LG M\u00fcnchen: <\/strong><strong>Verbot gilt auch f\u00fcr Altvertr\u00e4ge<\/strong><\/h2>\n<p>Das LG M\u00fcnchen I hat der Klage der vzbv stattgegeben. Nach Auffassung des Gerichts k\u00f6nnen Kunden ihre Rechnungen ohne Zusatzkosten per SEPA-\u00dcberweisung bezahlen \u2013 unabh\u00e4ngig davon, wann sie ihren Vertrag abgeschlossen haben<em>.<\/em> Eine andere Regelung in AGB versto\u00dfe gegen\u00a0<a href=\"https:\/\/www.gesetze-im-internet.de\/bgb\/__270a.html\">\u00a7 270a BGB<\/a>\u00a0und sei unzul\u00e4ssig.<\/p>\n<p>Zwar bestimme das Gesetz ausdr\u00fccklich, dass die Rechtsnorm nur auf Vertr\u00e4ge anzuwenden sei, die ab dem 13. Januar 2018 entstanden seien. Hierunter fielen aber auch Dauerschuldverh\u00e4ltnisse wie im vorliegenden Fall. Andernfalls w\u00fcrden Bestandskunden und Neukunden unterschiedlich rechtlich behandelt, was unangemessen w\u00e4re. Denn ein effektiver Verbraucherschutz und ein funktionierender Binnenmarkt kann nur gew\u00e4hrleistet werden, wenn das Geb\u00fchrenverbot unterschiedslos f\u00fcr Alt- und Neuvertr\u00e4ge angewendet werde, so das Gericht. Dies entspreche dem Zweck der EU-Richtlinie und dem Willen des deutschen Gesetzgebers.<\/p>\n<p>Ob Betroffene nun bereits zu viel gezahlte Betr\u00e4ge zur\u00fcckfordern k\u00f6nnen ist noch offen. Denn bislang ist das Urteil noch nicht rechtskr\u00e4ftig.<\/p>\n<h2>Fazit<\/h2>\n<p>Das Urteil soll alle betroffenen Unternehmen im E-Commerce darauf aufmerksam machen, die geltenden AGB und technischen Systeme der neuen Rechtslage anzupassen. Wer nach Inkrafttreten des neuen Gesetztes weiterhin Zusatzgeb\u00fchren f\u00fcr bestimmte Zahlungsarten verlangt, muss mit erheblichen wettbewerbsrechtlichen Abmahnungen rechnen. Werden solche Geb\u00fchren ohne Rechtsgrund erhoben, kann der betroffene Kunde diese zur\u00fcckverlangen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit 2018 d\u00fcrfen Unternehmen keine zus\u00e4tzlichen Entgelte f\u00fcr die Bezahlung via SEPA-\u00dcberweisungen, SEPA-Lastschriften oder Kredit- und Girokarten mehr fordern. Das Geb\u00fchrenverbot gilt auch f\u00fcr Altvertr\u00e4ge, die noch vor Inkrafttreten des\u00a0\u201eGesetzes zur Umsetzung der Zweiten Zahlungsdiensterichtlinie\u201c im Januar 2018 abgeschlossen wurden. Das entschied das LG M\u00fcnchen I nach einer Klage des Verbraucherzentrale Bundesverbands (vzbv) gegen Vodafone [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[15],"tags":[18097,18098,18099,18100],"class_list":["post-50139","post","type-post","status-publish","format-standard","hentry","category-wettbewerbsrecht-kartellrecht","tag-selbstzahlerpauschale","tag-zahlungsdiensterichtlinie","tag-zahlungsentgelt","tag-sepa-uebereisung"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/50139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/comments?post=50139"}],"version-history":[{"count":0,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/50139\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media?parent=50139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/categories?post=50139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/tags?post=50139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}