{"id":39681,"date":"2018-06-21T07:27:05","date_gmt":"2018-06-21T06:27:05","guid":{"rendered":"https:\/\/www.lhr-law.de?p=39681"},"modified":"2018-06-19T22:28:41","modified_gmt":"2018-06-19T21:28:41","slug":"olg-dresden-bezeichnung-von-seenotrettern-als-schlepper-ist-keine-schmaehkritik","status":"publish","type":"post","link":"https:\/\/www.lhr-law.de\/en\/magazin\/medienrecht-und-persoenlichkeitsrecht\/olg-dresden-bezeichnung-von-seenotrettern-als-schlepper-ist-keine-schmaehkritik\/","title":{"rendered":"OLG Dresden: Bezeichnung von Seenotrettern als Schlepper ist keine Schm\u00e4hkritik"},"content":{"rendered":"<figure id=\"attachment_37383\" aria-describedby=\"caption-attachment-37383\" style=\"width: 424px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-37383 size-full\" src=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2018\/01\/Fotolia_178366409_XS.jpg\" alt=\"Seenotretter als Schlepper\" width=\"424\" height=\"283\" srcset=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2018\/01\/Fotolia_178366409_XS.jpg 424w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2018\/01\/Fotolia_178366409_XS-90x60.jpg 90w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><figcaption id=\"caption-attachment-37383\" class=\"wp-caption-text\">\u00a9 calypso77 &#8211; fotolia.com<\/figcaption><\/figure>\n<p><em>Wer die Beitr\u00e4ge eines anderen auf Social-Media, mit einem zustimmenden Kommentar versehen, teilt, macht sich diese zu Eigen. Die Bezeichnung von Seenotrettern als \u201eSchlepper\u201c sei jedoch keine Schm\u00e4hkritik. Die Meinungsfreiheit \u00fcberwiege in diesem Fall das <a href=\"https:\/\/www.lhr-law.de\/rechtsgebiete\/medienrecht-persoenlichkeitsrecht\">Pers\u00f6nlichkeitsrecht<\/a> der Hilfsorganisation, so das Oberlandesgericht Dresden.<\/em><\/p>\n<h2>\u201eMission Lifeline\u201c als \u201eSchlepper\u201c?<\/h2>\n<p>Ausl\u00f6ser f\u00fcr das Verfahren war, dass der \u201ePegida-F\u00f6rderverein\u201c und ein Vorsitzender des Vereins auf Facebook einen Artikel der \u201eIdentit\u00e4ren Bewegung Dresden\u201c geteilt hatten. In diesem Beitrag wurde die Hilfsorganisation \u201eMission Lifeline\u201c als \u201eSchlepper\u201c, \u201eSchlepperorganisation\u201c und Schlepper-NGO\u201c bezeichnet. Ihre Posts versahen beide mit der Aussage \u201ewichtige und richtige Aktion\u201c. \u00dcber das <a href=\"https:\/\/www.lhr-law.de\/magazin\/medienrecht-und-persoenlichkeitsrecht\/lg-dresden-seenotretter-sind-keine-schlepper\">Urteil des Landgerichts Dresden in diesem Fall<\/a> haben wir bereits berichtet. Jetzt hat das Oberlandesgericht die erlassenen Unterlassungsurteile aufgehoben (OLG Dresden, Urteile v. 1.6.2018, Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=4%20U%20217\/18\" title=\"OLG Dresden, 01.06.2018 - 4 U 217\/18: Rechtsschutzbed&uuml;rfnis f&uuml;r eine Klage auf Unterlassung ein...\">4 U 217\/18<\/a> und <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=4%20U%20218\/18\" title=\"4 U 218\/18 (2 zugeordnete Entscheidungen)\">4 U 218\/18<\/a>).<\/p>\n<h2>Seenotretter gegen Pegida<\/h2>\n<p>Die einstweilige Verf\u00fcgung gegen Pegida wiesen die Richter bereits als unzul\u00e4ssig zur\u00fcck. Es bestehe kein Rechtsschutzbed\u00fcrfnis, da bereits ein Unterlassungstitel vorliege. Dieser beruhe auf einem, in einem fr\u00fcheren Verfahren geschlossenen, Vergleich zwischen den Parteien. In diesem Vergleich hatte sich Pegida verpflichtet die \u201eMission Lifeline\u201c nicht als \u201ekriminell agierende, private Schlepperorganisation\u201c zu bezeichnen.<\/p>\n<p>Nach Auffassung der Richter stelle die hier getroffene Aussage einen kerngleichen Versto\u00df dar. Die Worte \u201eSchlepper\u201c und \u201eSchlepperorganisation\u201c seien f\u00fcr den angesprochenen Personenkreis ohnehin mit einem Strafbarkeitsvorwurf versehen. Durch diese Tatsache sei der Zusatz \u201ekriminell agierend\u201c entbehrlich um einen Versto\u00df zu bejahen.<\/p>\n<p>Im Ergebnis h\u00e4tte ein Vollstreckungsverfahren nach <a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/890.html\" title=\"&sect; 890 ZPO: Erzwingung von Unterlassungen und Duldungen\">\u00a7 890 ZPO<\/a> angestrengt werden m\u00fcssen und keine einstweilige Verf\u00fcgung.<\/p>\n<h2>Seenotretter gegen Siegfried D\u00e4britz<\/h2>\n<p>Die einstweilige Verf\u00fcgung gegen den Pegida-Vize-Vorsitzenden Siegfried D\u00e4britz sei hingegen zwar zul\u00e4ssig, jedoch unbegr\u00fcndet.<\/p>\n<p>D\u00e4britz habe sich die \u00c4u\u00dferung der Identit\u00e4ren Bewegung durch das Teilen mit dem Kommentar zu eigen gemacht. Zwar sei das Teilen von Beitr\u00e4gen auf Social-Media-Plattformen generell eine wertungsfreie Handlung, durch den Kommentar \u201ewichtige und richtige Aktion\u201c werde allerdings die inhaltliche \u00dcbernahme des Artikelinhalts eindeutig ersichtlich.<\/p>\n<p>Der Post sei als eine Meinungs\u00e4u\u00dferung zu qualifizieren, wodurch der Anwendungsbereich der Meinungsfreiheit <a href=\"https:\/\/dejure.org\/gesetze\/GG\/5.html\" title=\"Art. 5 GG\">Art. 5 GG<\/a> er\u00f6ffnet ist. Bei der Abgrenzung zwischen Tatsachenbehauptung und Meinungs\u00e4u\u00dferung stellten die Richter nur auf den Facebook-Post ab, nicht aber auf den gesamten Artikel. Es sei dem Post kein ausreichender Tatsachenkern f\u00fcr eine Tatsachenbehauptung zu entnehmen. \u201eMission Lifeline\u201c werde keine Straftat \u2013 im Sinne des <a href=\"https:\/\/dejure.org\/gesetze\/AufenthG\/96.html\" title=\"&sect; 96 AufenthG: Einschleusen von Ausl&auml;ndern und Personen, auf die das Freiz&uuml;gigkeitsgesetz\/EU Anwendung findet\">\u00a7 96 Abs. 2 AufenthG<\/a> dem \u201egewerbsm\u00e4\u00dfigen Einschleusen\u201c \u2013 unterstellt. Es handle sich vielmehr um Bewertungen und Meinungen zu dem Handeln der Hilfsorganisation. Alle anderen \u00c4u\u00dferungen bez\u00f6gen sich nicht nur auf die Kl\u00e4gerin, sondern auf alle Seenotorganisationen. Insgesamt sei der tats\u00e4chliche Gehalt zu inhaltsleer und substanzarm f\u00fcr eine Beweisaufnahme. Der Einordnung als Meinungs\u00e4u\u00dferung stehe auch die laienhafte Einordnung als strafbares Verhalten nicht entgegen.<\/p>\n<h2>Schm\u00e4hkritik oder noch Meinung?<\/h2>\n<p>Der Bundesgerichtshof betont in st\u00e4ndiger Rechtsprechung, dass nicht jede Meinungs\u00e4u\u00dferung, die \u00fcberspitzt, geschmackslos oder ausf\u00e4llig ist Schm\u00e4hkritik darstellt. Dies setze vielmehr voraus, dass der Betroffene in einer Weise angeprangert wird, dass der sachliche Inhalt der Aussage vollkommen hinter die Diffamierung der Person zur\u00fccktritt. Dies sei aber vorliegenden nicht der Fall, da nicht die Mitarbeiter, sondern die Hilfsorganisation als solche angesprochen werde, so die Richter. Das allgemeine Pers\u00f6nlichkeitsrecht einer juristischen Person fu\u00dfe nicht auf der Menschenw\u00fcrde und diese habe weder eine Intim-, noch eine Privatsph\u00e4re. Jegliche \u00c4u\u00dferung k\u00f6nne daher h\u00f6chstens ein Eingriff in die Sozialsph\u00e4re darstellen.<\/p>\n<p>Ein solcher Eingriff k\u00f6nne nur dann als Schm\u00e4hkritik gewertet werden, wenn die juristische Person in ihrer sozialen oder wirtschaftlichen Existenz bedroht sei. Dies sei vorliegend nicht der Fall. Erg\u00e4nzend legten die Richter dar, dass in diesem Fall die Annahme von Schm\u00e4hkritik auch in Bezug auf eine nat\u00fcrliche Person ausscheide. Die Diffamierung der Seenotretter stehe nicht im Vordergrund, sondern die ablehnende Haltung zur Seenotrettung von Fl\u00fcchtlingen im Mittelmeer.<\/p>\n<p>Bei der Grundrechtsabw\u00e4gung \u00fcberwiege daher die Meinungsfreiheit das allgemeine Pers\u00f6nlichkeitsrecht. Es sei keine Prangerwirkung \u00fcber den Personenkreis, der die Ansicht Pegidas teile, hinaus zu erwarten. Au\u00dferdem sei nur die Sozialsph\u00e4re durch die im \u00fcbrigen substanzarme \u00c4u\u00dferung betroffen. Die Meinungsfreiheit sei allerdings in ihrem Kern betroffen und jeder Eingriff in diese auf das unbedingt Erforderliche zu begrenzen.<\/p>\n<h2>Fazit<\/h2>\n<p>Einerseits l\u00e4sst sich sagen, dass sich die Substanzarmut des Beitrages in diesem Fall gelohnt hat. Ab und zu ist es wohl besser, keine Tatsachenbehauptungen aufzustellen, wenn man die Grenzen der Meinungsfreiheit ausreizen will. Bez\u00fcglich der einstweiligen Verf\u00fcgung gegen Pegida selbst liegt bereits ein Fehler in der Prozesstaktik vor, da der kerngleiche Versto\u00df hier relativ offensichtlich war. Jetzt muss ein weiteres Verfahren angestrengt werden um zumindest ein Ziel \u2013 das Ordnungsgeld gegen Pegida \u2013 zu erreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer die Beitr\u00e4ge eines anderen auf Social-Media, mit einem zustimmenden Kommentar versehen, teilt, macht sich diese zu Eigen. Die Bezeichnung von Seenotrettern als \u201eSchlepper\u201c sei jedoch keine Schm\u00e4hkritik. Die Meinungsfreiheit \u00fcberwiege in diesem Fall das Pers\u00f6nlichkeitsrecht der Hilfsorganisation, so das Oberlandesgericht Dresden. \u201eMission Lifeline\u201c als \u201eSchlepper\u201c? Ausl\u00f6ser f\u00fcr das Verfahren war, dass der \u201ePegida-F\u00f6rderverein\u201c und [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":37383,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[13,1229],"tags":[110,17182,17407],"class_list":["post-39681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medienrecht-und-persoenlichkeitsrecht","category-social-media-recht","tag-schmahkritik","tag-seenotretter","tag-pegida"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/39681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/comments?post=39681"}],"version-history":[{"count":0,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/39681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media\/37383"}],"wp:attachment":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media?parent=39681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/categories?post=39681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/tags?post=39681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}