{"id":316,"date":"2008-05-06T11:25:00","date_gmt":"2008-05-06T09:25:00","guid":{"rendered":"https:\/\/www.lhr-law.de\/wordpress\/?p=316"},"modified":"2017-03-12T21:26:22","modified_gmt":"2017-03-12T20:26:22","slug":"markeninhaber-missbrauchen-ebay","status":"publish","type":"post","link":"https:\/\/www.lhr-law.de\/en\/magazin\/markeninhaber-missbrauchen-ebay\/","title":{"rendered":"Markeninhaber missbrauchen eBay"},"content":{"rendered":"<p><!--:de-->Der Bundesgerichtshof hat es <a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=pm&amp;Datum=2008&amp;Sort=3&amp;nr=43650&amp;anz=92&amp;pos=4&amp;Blank=1\">k\u00fcrzlich noch einmal klargestellt<\/a>: eBay haftet gegen\u00fcber Markeninhabern als &#8220;St\u00f6rer&#8221; zumindest auf Unterlassung, wenn eBay-H\u00e4ndler das Markenrecht verletzen. Das ist etwa dann der Fall, wenn Markenware importiert wird, die nicht f\u00fcr die EU bestimmt ist oder F\u00e4lschungen angeboten werden. Allerdings setzt solch eine Haftung von eBay auch einen tats\u00e4chlichen Versto\u00df voraus. eBay ist also in keinem Fall verpflichtet, Auktionen zu l\u00f6schen, die nicht auch tats\u00e4chlich das Markenrecht verletzen.<\/p>\n<p>In letzter Zeit <a href=\"https:\/\/www.lhr-law.de\/lbr-blog\/2006\/11\/markeninhaber-loschen-rechtmasige-ebay-auktionen\/\">h\u00e4ufen sich bei uns wieder die F\u00e4lle<\/a>, in denen Markeninhaber unerw\u00fcnschte Auktionen &#8211; v\u00f6llig unberechtigt &#8211; mittels eBay l\u00f6schen lassen. M\u00f6glich macht es das <a href=\"http:\/\/pages.ebay.de\/vero\/index.html?ssPageName=home:f:f:DE&amp;_trksid=p3907.m36\">VeRI (Verifizierte Rechteinhaber-Programm) von eBay<\/a>, das eingef\u00fchrt wurde, um Verst\u00f6\u00dfen gegen Schutzrechte m\u00f6glichst wirkungsvoll zu begegnen. Vielleicht zu wirkungsvoll: Es reicht n\u00e4mlich aus, dass Inhaber von angeblichen Schutzrechten eine &#8220;eidesstattliche Versicherung&#8221; abgeben (die tats\u00e4chlich keine eidesstattliche Versicherung ist) und dann angebliche Verst\u00f6\u00dfe gegen Marken- oder Urheberrecht per E-Mail bei eBay melden. In der Regel wird die Auktion daraufhin sofort gel\u00f6scht.<\/p>\n<p>Ob tats\u00e4chlich eine Markenrechtsverletzung vorliegt, pr\u00fcft eBay dabei nicht und kann es in den meisten F\u00e4llen auch nicht. eBay sitzt damit in der Zwickm\u00fchle und muss sich entweder f\u00fcr den meist m\u00e4chtigeren Markeninhaber oder den kleinen Verk\u00e4ufer entscheiden. So ist es m\u00f6glich, dass ein Markeninhaber, dessen Markenrecht an der Ware <a href=\"http:\/\/bundesrecht.juris.de\/markeng\/__24.html\">ersch\u00f6pft<\/a> und damit wertlos ist Auktionen l\u00f6schen l\u00e4sst, ohne dazu rechtlich berechtigt zu sein. Ein einfaches, effektives wie illegales Vorgehen, wenn einem Hersteller ein bestimmter Vertriebskanal nicht passt und er vielleicht sogar genau wei\u00df, dass auf dem Rechtsweg nichts zu machen ist.<\/p>\n<p>Das fatale an diesem System ist, dass hartn\u00e4ckige Markeninhaber durch viele unberechtigte L\u00f6schungen irgendwann sogar den Ausschluss &#8220;unerw\u00fcnschter&#8221; Verk\u00e4ufer von der eBay-Plattform provozieren k\u00f6nnen. Das kann Existenzen vernichten. Denn wenn sich die Auktionsl\u00f6schungen h\u00e4ufen, l\u00f6st dies ab einer gewissen Anzahl bei eBay offenbar eine vollautomatische Verbannung des H\u00e4ndlers aus. Viele Verk\u00e4ufer nehmen das hin &#8211; obwohl gute Chancen bestehen, sich gegen ein solches Vorgehen zur Wehr zu setzen:<\/p>\n<p>Behauptet ein Markeninhaber n\u00e4mlich wider besseres Wissen eine Markenverletzung gegen\u00fcber eBay, um die L\u00f6schung von Auktionen zu erreichen, so kann darin ein Behinderungswettbewerb liegen (<a href=\"http:\/\/www.gesetze-im-internet.de\/uwg_2004\/__4.html\">\u00a7 4 Nr. 10 UWG<\/a>). Mittlerweile haben wir f\u00fcr unsere Mandanten in vergleichbaren F\u00e4llen einstweilige Verf\u00fcgungen erwirkt. Denkbar sind auch Schadensersatzanspr\u00fcche gegen den Markeninhaber, der unberechtigt l\u00f6schen l\u00e4sst. In keinem Fall sollten Verk\u00e4ufer unt\u00e4tig bleiben, wenn sie von eBay die ber\u00fchmte E-Mail: &#8220;Ihre Auktion wurde gel\u00f6scht&#8221; erhalten&#8230; (zie)<\/p>\n<p><a href=\"http:\/\/www.lampmannbehn.de\/blog\/2006\/11\/markeninhaber-lschen-rechtmige-ebay.html\">mehr zum Thema<\/a><!--:--><!--:en--><\/p>\n<div style=\"text-align: justify\">Der Bundesgerichtshof hat es <a href=\"http:\/\/juris.bundesgerichtshof.de\/cgi-bin\/rechtsprechung\/document.py?Gericht=bgh&amp;Art=pm&amp;Datum=2008&amp;Sort=3&amp;nr=43650&amp;anz=92&amp;pos=4&amp;Blank=1\">k\u00fcrzlich noch einmal klargestellt<\/a>: eBay haftet gegen\u00fcber Markeninhabern als &#8220;St\u00f6rer&#8221; zumindest auf Unterlassung, wenn eBay-H\u00e4ndler das Markenrecht verletzen. Das ist etwa dann der Fall, wenn Markenware importiert wird, die nicht f\u00fcr die EU bestimmt ist oder F\u00e4lschungen angeboten werden. Allerdings setzt solch eine Haftung von eBay auch einen tats\u00e4chlichen Versto\u00df voraus. eBay ist also in keinem Fall verpflichtet, Auktionen zu l\u00f6schen, die nicht auch tats\u00e4chlich das Markenrecht verletzen.<\/div>\n<p style=\"text-align: justify\">In letzter Zeit <a href=\"https:\/\/www.lhr-law.de\/lbr-blog\/2006\/11\/markeninhaber-loschen-rechtmasige-ebay-auktionen\/\">h\u00e4ufen sich bei uns wieder die F\u00e4lle<\/a>, in denen Markeninhaber unerw\u00fcnschte Auktionen &#8211; v\u00f6llig unberechtigt &#8211; mittels eBay l\u00f6schen lassen. M\u00f6glich macht es das <a href=\"http:\/\/pages.ebay.de\/vero\/index.html?ssPageName=home:f:f:DE&amp;_trksid=p3907.m36\">VeRI (Verifizierte Rechteinhaber-Programm) von eBay<\/a>, das eingef\u00fchrt wurde, um Verst\u00f6\u00dfen gegen Schutzrechte m\u00f6glichst wirkungsvoll zu begegnen. Vielleicht zu wirkungsvoll: Es reicht n\u00e4mlich aus, dass Inhaber von angeblichen Schutzrechten eine &#8220;eidesstattliche Versicherung&#8221; abgeben (die tats\u00e4chlich keine eidesstattliche Versicherung ist) und dann angebliche Verst\u00f6\u00dfe gegen Marken- oder Urheberrecht per E-Mail bei eBay melden. In der Regel wird die Auktion daraufhin sofort gel\u00f6scht.<\/p>\n<p style=\"text-align: justify\">Ob tats\u00e4chlich eine Markenrechtsverletzung vorliegt, pr\u00fcft eBay dabei nicht und kann es in den meisten F\u00e4llen auch nicht. eBay sitzt damit in der Zwickm\u00fchle und muss sich entweder f\u00fcr den meist m\u00e4chtigeren Markeninhaber oder den kleinen Verk\u00e4ufer entscheiden. So ist es m\u00f6glich, dass ein Markeninhaber, dessen Markenrecht an der Ware <a href=\"http:\/\/bundesrecht.juris.de\/markeng\/__24.html\">ersch\u00f6pft<\/a> und damit wertlos ist Auktionen l\u00f6schen l\u00e4sst, ohne dazu rechtlich berechtigt zu sein. Ein einfaches, effektives wie illegales Vorgehen, wenn einem Hersteller ein bestimmter Vertriebskanal nicht passt und er vielleicht sogar genau wei\u00df, dass auf dem Rechtsweg nichts zu machen ist.<\/p>\n<p style=\"text-align: justify\">Das fatale an diesem System ist, dass hartn\u00e4ckige Markeninhaber durch viele unberechtigte L\u00f6schungen irgendwann sogar den Ausschluss &#8220;unerw\u00fcnschter&#8221; Verk\u00e4ufer von der eBay-Plattform provozieren k\u00f6nnen. Das kann Existenzen vernichten. Denn wenn sich die Auktionsl\u00f6schungen h\u00e4ufen, l\u00f6st dies ab einer gewissen Anzahl bei eBay offenbar eine vollautomatische Verbannung des H\u00e4ndlers aus. Viele Verk\u00e4ufer nehmen das hin &#8211; obwohl gute Chancen bestehen, sich gegen ein solches Vorgehen zur Wehr zu setzen:<\/p>\n<p style=\"text-align: justify\">Behauptet ein Markeninhaber n\u00e4mlich wider besseres Wissen eine Markenverletzung gegen\u00fcber eBay, um die L\u00f6schung von Auktionen zu erreichen, so kann darin ein Behinderungswettbewerb liegen (<a href=\"http:\/\/www.gesetze-im-internet.de\/uwg_2004\/__4.html\">\u00a7 4 Nr. 10 UWG<\/a>). Mittlerweile haben wir f\u00fcr unsere Mandanten in vergleichbaren F\u00e4llen einstweilige Verf\u00fcgungen erwirkt. Denkbar sind auch Schadensersatzanspr\u00fcche gegen den Markeninhaber, der unberechtigt l\u00f6schen l\u00e4sst. In keinem Fall sollten Verk\u00e4ufer unt\u00e4tig bleiben, wenn sie von eBay die ber\u00fchmte E-Mail: &#8220;Ihre Auktion wurde gel\u00f6scht&#8221; erhalten&#8230; (zie)<\/p>\n<p><a href=\"http:\/\/www.lampmannbehn.de\/blog\/2006\/11\/markeninhaber-lschen-rechtmige-ebay.html\">mehr zum Thema<\/a><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bundesgerichtshof hat es k\u00fcrzlich noch einmal klargestellt: eBay haftet gegen\u00fcber Markeninhabern als &#8220;St\u00f6rer&#8221; zumindest auf Unterlassung, wenn eBay-H\u00e4ndler das Markenrecht verletzen. Das ist etwa dann der Fall, wenn Markenware importiert wird, die nicht f\u00fcr die EU bestimmt ist oder F\u00e4lschungen angeboten werden. Allerdings setzt solch eine Haftung von eBay auch einen tats\u00e4chlichen Versto\u00df voraus. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1,13],"tags":[],"class_list":["post-316","post","type-post","status-publish","format-standard","hentry","category-magazin","category-medienrecht-und-persoenlichkeitsrecht"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":0,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/316\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media?parent=316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/categories?post=316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/tags?post=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}