{"id":17587,"date":"2013-04-24T07:46:36","date_gmt":"2013-04-24T06:46:36","guid":{"rendered":"https:\/\/www.lhr-law.de\/?p=17587"},"modified":"2017-04-07T11:20:40","modified_gmt":"2017-04-07T10:20:40","slug":"sie-ist-da-die-erste-einstweilige-verfugung-bezuglich-eines-fehlenden-impressums-auf-google","status":"publish","type":"post","link":"https:\/\/www.lhr-law.de\/en\/magazin\/sie-ist-da-die-erste-einstweilige-verfugung-bezuglich-eines-fehlenden-impressums-auf-google\/","title":{"rendered":"Erste einstweilige Verf\u00fcgung bez\u00fcglich eines fehlenden Impressums auf Google+"},"content":{"rendered":"<p><!--:de--><a href=\"https:\/\/www.lhr-law.de\/magazin\/sie-ist-da-die-erste-einstweilige-verfugung-bezuglich-eines-fehlenden-impressums-auf-google\/attachment\/googleabmahnung\" rel=\"attachment wp-att-17592\"><img decoding=\"async\" class=\"alignleft size-full wp-image-17592\" title=\"Jetzt auch google+\" src=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2013\/04\/googleabmahnung.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.lhr-law.de\/wp-content\/uploads\/2013\/04\/googleabmahnung.jpg 150w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2013\/04\/googleabmahnung-44x44.jpg 44w, https:\/\/www.lhr-law.de\/wp-content\/uploads\/2013\/04\/googleabmahnung-90x90.jpg 90w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>Es war nur eine Frage der Zeit, bis nach den Impressumssabmahnungen auf Facebook (wir berichteten unter anderem <a href=\"https:\/\/www.lhr-law.de\/magazin\/massenabmahner-bittet-sich-diskretion-aus\" target=\"_blank\">hier<\/a>) auch Google + ins Visier genommen werden w\u00fcrde.<\/p>\n<p>Rechtsanwalt Daniel <a href=\"http:\/\/www.multimediarechtler.de\/impressumspflicht-internetpraesenz-google-plu\/\">berichtete letzte Woche<\/a> auf seiner Homepage davon, dass das Landgericht Berlin auf seinen Antrag hin eine einstweilige Verf\u00fcgung erlassen hat.<\/p>\n<p>Damit wird dem Antragsgegner bei Meidung eines Ordnungsgelds von bis zu 250.000 \u20ac verboten , auf der gesch\u00e4ftlich genutzten Internetpr\u00e4senz bei google+ nicht die Pflichtangaben zur Anbieterkennzeichnung nach <a href=\"https:\/\/dejure.org\/gesetze\/TMG\/5.html\" title=\"&sect; 5 TMG: Allgemeine Informationspflichten\">\u00a7 5 TMG<\/a> (Impressumspflicht) leicht erkennbar, unmittelbar erreichbar und st\u00e4ndig verf\u00fcgbar zu halten. (LG Berlin, Beschluss v. 28.03.2013, Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=16%20O%20154\/13\" title=\"LG Berlin, 28.03.2013 - 16 O 154\/13: Impressumspflicht auch bei Google-plus\">16 O 154\/13<\/a>)<\/p>\n<p>Der Antragsgegner hatte auf seiner gesch\u00e4ftlich genutzten Internetpr\u00e4senz unter google+ offenbar keine (vollst\u00e4ndigen) Angaben zur Anbieterkennzeichnung hinterlegt.<\/p>\n<p>Eigentlich nichts Besonderes, sollte man meinen. Der Teufel steckt jedoch, wie so h\u00e4ufig, im Detail.<\/p>\n<p><b>Das Landgericht wollte zun\u00e4chst nicht erlassen <\/b><\/p>\n<p>Das Landgericht Berlin wollte die begehrte einstweilige Verf\u00fcgung jedoch offenbar zuerst nicht erlassen. W\u00f6rtlich schrieb das Landgericht Berlin in einem Hinweisbeschluss:<\/p>\n<blockquote><p>\u201eDie Kammer h\u00e4lt daf\u00fcr, dass es sich in solchen F\u00e4llen um eine reine Bagatelle handelt, weil eine Umgehung des Verbraucherschutzes hier nicht im Vordergrund steht, sondern die Verkehrskreise erkennen, dass mit diesem Profil nur die Aufmerksamkeit auf die offizielle Homepage gelenkt werden soll.<\/p>\n<p>Anders s\u00e4he der Fall hingegen aus, wenn die offizielle Homepage nicht optisch in den Vordergrund ger\u00fcckt wird.<\/p>\n<p>Bei einer Kontrolle im Internet habe die Kammer im \u00fcbrigen festgestellt, dass sich auf der offiziellen Homepage der Beklagten der Hinweis findet, wonach das dortige Impressum auch f\u00fcr die Auftritte in sozialen Netzwerken gilt.\u201c<\/p><\/blockquote>\n<p>Abgesehen davon, dass es befremdet, dass sich die Kammer offenbar dazu berufen f\u00fchlte, \u00fcber den vorgetragenen Sachverhalts hinaus selbst Nachforschungen im Internet anzustellen &#8211; ein vor dem Hintergrund des Beibringungsgrundsatzes selbstverst\u00e4ndlich unzul\u00e4ssiges Verhalten des Gerichts &#8211; ist eine solche Auffassung, worauf der Kollege Daniel zu Recht hinweist, europarechtswidrig. Dennoch versuchen Gerichte oft sich mit dem Hinweis darauf, dass der monierte Rechtsversto\u00df eine Bagatelle sei, einer Entscheidung \u00fcber unliebsame Internetf\u00e4lle zu entziehen.<\/p>\n<p><b>Europarecht: Verbraucherinfos bez\u00fcglich kommerzieller Kommunikation sind wesentlich<br \/>\n<\/b><\/p>\n<p>Nach Artikel 7 Abs. 1 der Richtlinie 2005\/29\/EG \u00fcber unlautere Gesch\u00e4ftspraktiken (nachfolgend &#8220;RL UGP&#8221;) gilt eine Gesch\u00e4ftspraxis als irref\u00fchrend, wenn sie im konkreten Fall unter Ber\u00fccksichtigung aller tats\u00e4chlichen Umst\u00e4nde und der Beschr\u00e4nkungen des Kommunikationsmediums wesentliche Informationen vorenth\u00e4lt, die der durchschnittliche Verbraucher je nach den Umst\u00e4nden ben\u00f6tigt, um eine informierte gesch\u00e4ftliche Entscheidung zu treffen, und die somit einen Durchschnittsverbraucher zu einer gesch\u00e4ftlichen Entscheidung veranlasst oder zu veranlassen geeignet ist, die er sonst nicht getroffen h\u00e4tte.<\/p>\n<p>Nach Artikel 7 Abs. 5 der RL UGP werden als wesentlich alle Informationen eingestuft, die das Gemeinschaftsrecht in Bezug auf die kommerzielle Kommunikation vorsieht einschlie\u00dflich Werbung oder Marketing, auf die in der nicht ersch\u00f6pfenden Liste des Anhangs II verwiesen wird.<\/p>\n<p>Zu solchen Informationen geh\u00f6ren nach Anhang II zu dieser Vorschrift gerade auch die Pflichtangaben des Art. 5 Abs. 1 der Richtlinie 2000\/31\/EG (&#8220;Richtlinie \u00fcber den elektronischen Gesch\u00e4ftsverkehr&#8221;).\u00a0 Art. 5 Abs. 1 bestimmt in den Ziffern a. b. und c., dass der Diensteanbieter den Nutzer seines Dienste den Namen, die geographische Anschrift, unter der der Diensteanbieter niedergelassen ist sowie\u00a0 Angaben, die es erm\u00f6glichen, schnell mit dem Diensteanbieter Kontakt aufzunehmen und unmittelbar und effizient mit ihm zu kommunizieren, einschlie\u00dflich seiner Adresse der elektronischen Post anzugebe leicht, unmittelbar und st\u00e4ndig verf\u00fcgbar machen muss.<\/p>\n<p>Das Landgericht durfte dem Antragsteller somit den Erlass einer einstweiligen Verf\u00fcgung nicht mit dem Argument verweigern, es handele sich dabei um eine blo\u00dfe Bagatelle.<\/p>\n<p><b>Dennoch: Beschluss des Landgerichts fehlerhaft <\/b><\/p>\n<p>Wenn der betreffende Tenor tats\u00e4chlich wie folgt lauten sollte, steht der Beschluss dennoch auf sehr wackligen Beinen:<\/p>\n<blockquote><p>\u201e(&#8230;)nicht die Pflichtangaben zur Anbieterkennzeichnung nach <a href=\"https:\/\/dejure.org\/gesetze\/TMG\/5.html\" title=\"&sect; 5 TMG: Allgemeine Informationspflichten\">\u00a7 5 TMG<\/a> (Impressumspflicht) leicht erkennbar, unmittelbar erreichbar und st\u00e4ndig verf\u00fcgbar zu halten.\u201c<\/p><\/blockquote>\n<p>Denn der Tenor orientiert sich damit nicht an der konkreten Verletzungsform sondern ersch\u00f6pft sich in der Wiedergabe der gesetzlichen Vorschrift, die zudem weitestgehend aus unbestimmten Rechtsbegriffen (\u201eleicht erkennbar\u201c, \u00a0\u201eunmittelbar erreichbar \u201eund \u201est\u00e4ndig verf\u00fcgbar\u201c) besteht. Es ist h\u00f6chstrichterlich gekl\u00e4rt, dass auf der Grundlage eines solchen Titels eine Vollstreckung unstatthaft w\u00e4re, da die Pr\u00fcfung, ob das streitgegenst\u00e4ndliche Verhalten rechtswidrig ist, die eigentlich im Erkenntnisverfahren durchgef\u00fchrt werden soll, dem Vollstreckungsgericht vorbehalten bliebe.<\/p>\n<p>Die Entscheidung ist daher der Sache richtig, d\u00fcrfte aber auf einen Widerspruch hin keinen Bestand haben.<\/p>\n<p><strong>Sicheres Impressum bei Google+<\/strong><\/p>\n<p>Dennoch sollte die Entscheidung nat\u00fcrlich zum Anlass genommen werden, &#8211; soweit noch nicht geschehen &#8211; die notwendigen Angaben auch einem etwa vorhandenen Profil auf Google+ hinzuzuf\u00fcgen. Der Kollege Thomas Schwenke <a href=\"http:\/\/rechtsanwalt-schwenke.de\/abmahnung-impressum-google-plus-anleitung\/\">gibt hier n\u00fctzliche Tipps<\/a>, wie das Einf\u00fcgen der entsprechenden Angaben in der Praxis umgesetzt werden kann.<\/p>\n<p>Elegantere L\u00f6sungen, wie zum Beispiel in Gestalt einer App, sind zur Zeit nicht in Sicht.<\/p>\n<p>(la)<!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es war nur eine Frage der Zeit, bis nach den Impressumssabmahnungen auf Facebook (wir berichteten unter anderem hier) auch Google + ins Visier genommen werden w\u00fcrde. Rechtsanwalt Daniel berichtete letzte Woche auf seiner Homepage davon, dass das Landgericht Berlin auf seinen Antrag hin eine einstweilige Verf\u00fcgung erlassen hat. Damit wird dem Antragsgegner bei Meidung eines [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17592,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1,15],"tags":[33,226,2452],"class_list":["post-17587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazin","category-wettbewerbsrecht-kartellrecht","tag-abmahnung","tag-impressum","tag-einstweilige-verfuegung"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/17587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/comments?post=17587"}],"version-history":[{"count":0,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/posts\/17587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media\/17592"}],"wp:attachment":[{"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/media?parent=17587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/categories?post=17587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lhr-law.de\/en\/wp-json\/wp\/v2\/tags?post=17587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}